{"id":243052,"date":"2022-11-09T15:23:01","date_gmt":"2022-11-09T15:23:01","guid":{"rendered":"https:\/\/onedesk.com\/videos\/plantillas-formularios-internos\/"},"modified":"2022-11-10T14:52:28","modified_gmt":"2022-11-10T14:52:28","slug":"plantillas-formularios-internos","status":"publish","type":"aiovg_videos","link":"https:\/\/onedesk.com\/es\/videos\/plantillas-formularios-internos\/","title":{"rendered":"Plantillas de tickets y tareas y formularios internos"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Las plantillas de elementos, tambi\u00e9n llamadas plantillas de tickets o tareas, se refieren a la capacidad de crear nuevos tickets o tareas con valores predeterminados o preestablecidos. Por ejemplo, es posible que desee crear una nueva tarea con la prioridad y la descripci\u00f3n ya establecidas, lo que le permitir\u00e1 ahorrar tiempo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En OneDesk, usted y sus usuarios pueden crear tickets o tareas con el formulario de creaci\u00f3n interno. Se accede a los formularios internos desde el bot\u00f3n &#8216;Agregar&#8217; en el men\u00fa superior. Tambi\u00e9n puede tener m\u00faltiples formularios para cada ticket o tipo de tarea. Cada uno de estos formularios puede tener diferentes propiedades, as\u00ed como valores predeterminados. La configuraci\u00f3n de m\u00faltiples formularios con valores predeterminados establecidos le permite a su equipo crear nuevos tickets o tareas r\u00e1pidamente. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Este video cubrir\u00e1 el uso de m\u00faltiples formularios para plantillas de elementos y c\u00f3mo configurar sus formularios internos con sus propiedades deseadas y valores predeterminados. Este video cubre configuraciones para formularios internos, a los que se accede desde el men\u00fa Agregar aqu\u00ed. Estos son solo para el usuario.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para configurar o crear un formulario interno, vaya a Administraci\u00f3n y Formularios. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aqu\u00ed encontrar\u00e1 los ajustes y la configuraci\u00f3n de su formulario. Los formularios se desglosan primero por tickets y tareas y luego se dividen a\u00fan m\u00e1s por cada ticket o tipo de tarea habilitado. Cada tipo de ticket o tarea puede tener m\u00faltiples formularios. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por ejemplo, aqu\u00ed tengo Boletos, luego debajo un tipo de boleto llamado &#8216;boleto&#8217; y dos formularios para ese tipo. El siguiente bloque es un tipo de ticket llamado &#8216;incorporaci\u00f3n&#8217;, con un formulario para este tipo. Puede ver, editar y crear nuevos formularios aqu\u00ed. Para obtener informaci\u00f3n sobre los tipos de tareas o tickets, consulte los art\u00edculos y videos relacionados.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Como se mencion\u00f3, un caso de uso com\u00fan para m\u00faltiples formularios son las plantillas de elementos. Las plantillas de elementos se refieren a la capacidad de crear un ticket\/tarea con la mayor\u00eda de las propiedades ya completadas para usted. Por ejemplo, puede tener un servicio com\u00fan que ofrece a sus clientes. Quiz\u00e1s, al crear un nuevo ticket para este servicio, casi siempre debe ir al mismo proyecto o incluir los mismos detalles. Esta situaci\u00f3n es un caso de uso perfecto para un formulario adicional. Puede crear un formulario independiente, con el nombre de este servicio, que tenga el proyecto y la descripci\u00f3n ya establecidos como valores predeterminados. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Veamos un ejemplo. Tengo este tipo de boleto llamado &#8216;incorporaci\u00f3n&#8217; aqu\u00ed. Digamos que tengo dos situaciones de incorporaci\u00f3n comunes, una para clientes y otra para empleados. Vamos a crear y configurar otro formulario para estos servicios de incorporaci\u00f3n. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Primero vamos a crear un nuevo formulario. Seleccione el bot\u00f3n crear un nuevo formulario en la parte superior de la p\u00e1gina de configuraci\u00f3n. Seleccione el tipo de elemento para el que desea crear el formulario, en este caso, el tipo de ticket de &#8216;incorporaci\u00f3n&#8217;. El formulario aparecer\u00e1 en su lista de formularios y ahora podemos editar el formulario. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Seleccione el icono de l\u00e1piz junto al formulario que desea editar para abrir la ventana emergente de edici\u00f3n del formulario.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">El nombre del men\u00fa es el nombre de su formulario tal como aparece en la configuraci\u00f3n de administraci\u00f3n, el men\u00fa Agregar y dentro del t\u00edtulo del formulario. Nombrar\u00e9 mi formulario, incorporaci\u00f3n de empleados. El t\u00edtulo del formulario se muestra dentro del formulario de creaci\u00f3n. Le dar\u00e9 un t\u00edtulo&#8230; Y el subt\u00edtulo se muestra debajo del t\u00edtulo del formulario dentro del formulario de creaci\u00f3n. Podemos a\u00f1adir alg\u00fan texto descriptivo aqu\u00ed. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Puede editar qu\u00e9 propiedades aparecer\u00e1n al crear el art\u00edculo utilizando este formulario. Seleccione &#8216;Agregar otra propiedad al formulario&#8217; para seleccionar una nueva propiedad. Para mi formulario de incorporaci\u00f3n de empleados, quiero mi campo personalizado &#8216;Departamento&#8217; aqu\u00ed, as\u00ed que lo agregaremos. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Pase el cursor sobre las filas de propiedades, luego haga clic y arrastre el \u00edcono a la izquierda del nombre de la propiedad para reordenar las propiedades. Esta acci\u00f3n reordena c\u00f3mo se muestran las propiedades en el formulario de creaci\u00f3n. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tambi\u00e9n puede establecer si una propiedad es obligatoria o no. Tenga en cuenta que el Nombre, el Proyecto y el Tipo son obligatorios de forma predeterminada. Voy a configurar el campo de mi departamento seg\u00fan sea necesario. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tambi\u00e9n puede eliminar una propiedad seleccionando el icono &#8216;X&#8217;. El Nombre, Proyecto y Tipo son campos obligatorios y no se pueden eliminar.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A continuaci\u00f3n, establezcamos valores predeterminados para las propiedades, lo que significa que esas propiedades se completar\u00e1n con esa informaci\u00f3n al crear el ticket\/tarea usando este formulario. Nota: a\u00fan puede editar un valor predeterminado antes de la creaci\u00f3n. Para establecer un valor predeterminado, coloque el cursor sobre la columna &#8220;Valor predeterminado&#8221; y seleccione el \u00edcono de l\u00e1piz que aparece para establecer el valor predeterminado. Digamos que para mi servicio de incorporaci\u00f3n de empleados aqu\u00ed, quiero que, de manera predeterminada, se asigne a alguien a este ticket y que tenga una descripci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cierra la ventana cuando est\u00e9s listo y tus cambios se guardar\u00e1n. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Finalmente, si cambia de opini\u00f3n o comete un error, puede eliminar un formulario haciendo clic en el icono de la papelera junto al formulario que desea eliminar. Tenga en cuenta que no puede eliminar su formulario predeterminado. Si desea eliminar el formulario, primero establezca un nuevo valor predeterminado. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ahora veamos c\u00f3mo se ve nuestra plantilla. Haga clic en el bot\u00f3n Agregar y crearemos un nuevo ticket utilizando el formulario de incorporaci\u00f3n de empleados que acabamos de configurar. Aqu\u00ed puedes ver las distintas configuraciones que realizamos. Nuestras propiedades, como el departamento, est\u00e1n incluidas y nuestros valores predeterminados son nuestro conjunto. Ahora es m\u00e1s f\u00e1cil crear un ticket de incorporaci\u00f3n de nuevo empleado. Si tiene alguna pregunta, no dude en comunicarse a trav\u00e9s del chat en vivo o en <\/span><span style=\"font-weight: 400;\">apoyo @onedesk.com<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las plantillas de elementos, tambi\u00e9n llamadas plantillas de tickets o tareas, se refieren a la capacidad de crear nuevos tickets o tareas con valores predeterminados o preestablecidos. Por ejemplo, es posible que desee crear una nueva tarea con la prioridad y la descripci\u00f3n ya establecidas, lo que le permitir\u00e1 ahorrar tiempo. En OneDesk, usted y [&hellip;]<\/p>\n","protected":false},"author":30,"comment_status":"closed","ping_status":"closed","template":"","meta":{"tpgb_global_settings":"","inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"aiovg_categories":[9843,9867,10260],"aiovg_tags":[],"class_list":["post-243052","aiovg_videos","type-aiovg_videos","status-publish","has-post-thumbnail","hentry","aiovg_categories-02-gestion-de-proyectos","aiovg_categories-03-configuracion-administrativa","aiovg_categories-13-cuenta-y-administracion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Plantillas de tickets o tareas y formularios internos | Videogu\u00eda de OneDesk<\/title>\n<meta name=\"description\" content=\"V\u00eddeo sobre c\u00f3mo crear y configurar formularios internos. Habilite m\u00faltiples formularios con valores predeterminados para crear r\u00e1pidamente nuevos tickets o tareas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onedesk.com\/es\/videos\/plantillas-formularios-internos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plantillas de tickets o tareas y formularios internos | Videogu\u00eda de OneDesk\" \/>\n<meta property=\"og:description\" content=\"V\u00eddeo sobre c\u00f3mo crear y configurar formularios internos. Habilite m\u00faltiples formularios con valores predeterminados para crear r\u00e1pidamente nuevos tickets o tareas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onedesk.com\/es\/videos\/plantillas-formularios-internos\/\" \/>\n<meta property=\"og:site_name\" content=\"Un escritorio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OneDeskApp\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-10T14:52:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onedesk.com\/wp-content\/uploads\/2020\/04\/OneDesk-Logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OneDeskApp\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Plantillas de tickets o tareas y formularios internos | Videogu\u00eda de OneDesk","description":"V\u00eddeo sobre c\u00f3mo crear y configurar formularios internos. Habilite m\u00faltiples formularios con valores predeterminados para crear r\u00e1pidamente nuevos tickets o tareas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onedesk.com\/es\/videos\/plantillas-formularios-internos\/","og_locale":"es_ES","og_type":"article","og_title":"Plantillas de tickets o tareas y formularios internos | Videogu\u00eda de OneDesk","og_description":"V\u00eddeo sobre c\u00f3mo crear y configurar formularios internos. Habilite m\u00faltiples formularios con valores predeterminados para crear r\u00e1pidamente nuevos tickets o tareas.","og_url":"https:\/\/onedesk.com\/es\/videos\/plantillas-formularios-internos\/","og_site_name":"Un escritorio","article_publisher":"https:\/\/www.facebook.com\/OneDeskApp","article_modified_time":"2022-11-10T14:52:28+00:00","og_image":[{"width":1280,"height":800,"url":"https:\/\/onedesk.com\/wp-content\/uploads\/2020\/04\/OneDesk-Logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@OneDeskApp","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/onedesk.com\/es\/videos\/plantillas-formularios-internos\/","url":"https:\/\/onedesk.com\/es\/videos\/plantillas-formularios-internos\/","name":"Plantillas de tickets o tareas y formularios internos | Videogu\u00eda de OneDesk","isPartOf":{"@id":"https:\/\/onedesk.com\/es\/#website"},"datePublished":"2022-11-09T15:23:01+00:00","dateModified":"2022-11-10T14:52:28+00:00","description":"V\u00eddeo sobre c\u00f3mo crear y configurar formularios internos. Habilite m\u00faltiples formularios con valores predeterminados para crear r\u00e1pidamente nuevos tickets o tareas.","breadcrumb":{"@id":"https:\/\/onedesk.com\/es\/videos\/plantillas-formularios-internos\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onedesk.com\/es\/videos\/plantillas-formularios-internos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/onedesk.com\/es\/videos\/plantillas-formularios-internos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Videos","item":"https:\/\/onedesk.com\/es\/videos\/"},{"@type":"ListItem","position":2,"name":"Plantillas de tickets y tareas y formularios internos"}]},{"@type":"WebSite","@id":"https:\/\/onedesk.com\/es\/#website","url":"https:\/\/onedesk.com\/es\/","name":"Un escritorio","description":"Software de gesti\u00f3n de proyectos y asistencia t\u00e9cnica","publisher":{"@id":"https:\/\/onedesk.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onedesk.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/onedesk.com\/es\/#organization","name":"Un escritorio","url":"https:\/\/onedesk.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/onedesk.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/onedesk.com\/wp-content\/uploads\/2016\/01\/white-logo-small.png","contentUrl":"https:\/\/onedesk.com\/wp-content\/uploads\/2016\/01\/white-logo-small.png","width":207,"height":40,"caption":"Un escritorio"},"image":{"@id":"https:\/\/onedesk.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OneDeskApp","https:\/\/x.com\/OneDeskApp","https:\/\/www.instagram.com\/onedeskapp\/","https:\/\/www.linkedin.com\/company\/onedesk-inc-1","https:\/\/www.pinterest.com\/onedesk\/","https:\/\/www.youtube.com\/user\/OneDeskApp"],"description":"OneDesk is a work management app for managing customer \/ end-user support, projects, and financials.","email":"support@onedesk.com","telephone":"1-855-663-3375","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}}]}},"tpgb_featured_images":{"default":"https:\/\/onedesk.com\/wp-content\/plugins\/the-plus-addons-for-block-editor\/assets\/images\/tpgb-placeholder.jpg"},"tpgb_post_meta_info":{"get_date":"November 9, 2022","get_modified_date":"November 10, 2022","category_list":{"aiovg_categories":[{"term_id":9843,"name":"02. Gesti\u00f3n de proyectos","slug":"02-gestion-de-proyectos","term_group":0,"term_taxonomy_id":9843,"taxonomy":"aiovg_categories","description":"Una colecci\u00f3n de videos para comenzar a usar las funciones de administraci\u00f3n de proyectos de OneDesk.","parent":9897,"count":20,"filter":"raw","term_order":"0"},{"term_id":9867,"name":"03. Configuraci\u00f3n administrativa","slug":"03-configuracion-administrativa","term_group":0,"term_taxonomy_id":9867,"taxonomy":"aiovg_categories","description":"Una colecci\u00f3n de videos para comenzar a personalizar su OneDesk a trav\u00e9s de la configuraci\u00f3n de administraci\u00f3n.","parent":9897,"count":11,"filter":"raw","term_order":"0"},{"term_id":10260,"name":"13. Cuenta y administraci\u00f3n","slug":"13-cuenta-y-administracion","term_group":0,"term_taxonomy_id":10260,"taxonomy":"aiovg_categories","description":"Obtenga informaci\u00f3n sobre las configuraciones, la configuraci\u00f3n de la cuenta, las preferencias de la empresa en su cuenta.","parent":9897,"count":5,"filter":"raw","term_order":"0"}],"aiovg_tags":false},"author_name":"Erin Richardson","author_url":"https:\/\/onedesk.com\/es\/author\/erin-richardsononedesk-com\/","author_email":"erin.richardson@onedesk.com","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"Erin","author_lastname":"Richardson","user_login":"erin.richardson@onedesk.com","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/5b43ac2756efc1d5aa46746163fa71ceee43f42a78652ebc70940d512d77cba0?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/5b43ac2756efc1d5aa46746163fa71ceee43f42a78652ebc70940d512d77cba0?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5b43ac2756efc1d5aa46746163fa71ceee43f42a78652ebc70940d512d77cba0?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":{"aiovg_categories":"<a href=\"https:\/\/onedesk.com\/video-category\/02-gestion-de-proyectos\/\" alt=\"02. Gesti\u00f3n de proyectos\"  class=\"aiovg_categories-02-gestion-de-proyectos\">02. Gesti\u00f3n de proyectos<\/a> <a href=\"https:\/\/onedesk.com\/video-category\/03-configuracion-administrativa\/\" alt=\"03. Configuraci\u00f3n administrativa\"  class=\"aiovg_categories-03-configuracion-administrativa\">03. Configuraci\u00f3n administrativa<\/a> <a href=\"https:\/\/onedesk.com\/video-category\/13-cuenta-y-administracion\/\" alt=\"13. Cuenta y administraci\u00f3n\"  class=\"aiovg_categories-13-cuenta-y-administracion\">13. Cuenta y administraci\u00f3n<\/a> "},"_links":{"self":[{"href":"https:\/\/onedesk.com\/es\/wp-json\/wp\/v2\/aiovg_videos\/243052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onedesk.com\/es\/wp-json\/wp\/v2\/aiovg_videos"}],"about":[{"href":"https:\/\/onedesk.com\/es\/wp-json\/wp\/v2\/types\/aiovg_videos"}],"author":[{"embeddable":true,"href":"https:\/\/onedesk.com\/es\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/onedesk.com\/es\/wp-json\/wp\/v2\/comments?post=243052"}],"wp:attachment":[{"href":"https:\/\/onedesk.com\/es\/wp-json\/wp\/v2\/media?parent=243052"}],"wp:term":[{"taxonomy":"aiovg_categories","embeddable":true,"href":"https:\/\/onedesk.com\/es\/wp-json\/wp\/v2\/aiovg_categories?post=243052"},{"taxonomy":"aiovg_tags","embeddable":true,"href":"https:\/\/onedesk.com\/es\/wp-json\/wp\/v2\/aiovg_tags?post=243052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}